{"id":704,"date":"2025-05-19T06:21:02","date_gmt":"2025-05-19T04:21:02","guid":{"rendered":"https:\/\/dallemolle.ch\/laureat\/2012\/"},"modified":"2025-11-13T11:22:46","modified_gmt":"2025-11-13T10:22:46","slug":"2012","status":"publish","type":"laureat","link":"https:\/\/dallemolle.ch\/it\/premiati\/2012\/","title":{"rendered":"Premiato 2012"},"template":"","meta":{"_acf_changed":false},"class_list":["post-704","laureat","type-laureat","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Premiato 2012 - Fondation Dalle Molle - La Fondation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dallemolle.ch\/it\/premiati\/2012\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premiato 2012 - Fondation Dalle Molle - La Fondation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dallemolle.ch\/it\/premiati\/2012\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Dalle Molle - La Fondation\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T10:22:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dallemolle.ch\\\/it\\\/premiati\\\/2012\\\/\",\"url\":\"https:\\\/\\\/dallemolle.ch\\\/it\\\/premiati\\\/2012\\\/\",\"name\":\"Premiato 2012 - Fondation Dalle Molle - La Fondation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dallemolle.ch\\\/it\\\/#website\"},\"datePublished\":\"2025-05-19T04:21:02+00:00\",\"dateModified\":\"2025-11-13T10:22:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dallemolle.ch\\\/it\\\/premiati\\\/2012\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dallemolle.ch\\\/it\\\/premiati\\\/2012\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dallemolle.ch\\\/it\\\/premiati\\\/2012\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dallemolle.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premiato 2012\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dallemolle.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/dallemolle.ch\\\/it\\\/\",\"name\":\"Fondation Dalle Molle - La Fondation\",\"description\":\"Pour la qualit\u00e9 de la vie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dallemolle.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premiato 2012 - Fondation Dalle Molle - La Fondation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dallemolle.ch\/it\/premiati\/2012\/","og_locale":"it_IT","og_type":"article","og_title":"Premiato 2012 - Fondation Dalle Molle - La Fondation","og_url":"https:\/\/dallemolle.ch\/it\/premiati\/2012\/","og_site_name":"Fondation Dalle Molle - La Fondation","article_modified_time":"2025-11-13T10:22:46+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dallemolle.ch\/it\/premiati\/2012\/","url":"https:\/\/dallemolle.ch\/it\/premiati\/2012\/","name":"Premiato 2012 - Fondation Dalle Molle - La Fondation","isPartOf":{"@id":"https:\/\/dallemolle.ch\/it\/#website"},"datePublished":"2025-05-19T04:21:02+00:00","dateModified":"2025-11-13T10:22:46+00:00","breadcrumb":{"@id":"https:\/\/dallemolle.ch\/it\/premiati\/2012\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dallemolle.ch\/it\/premiati\/2012\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dallemolle.ch\/it\/premiati\/2012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dallemolle.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Premiato 2012"}]},{"@type":"WebSite","@id":"https:\/\/dallemolle.ch\/it\/#website","url":"https:\/\/dallemolle.ch\/it\/","name":"Fondation Dalle Molle - La Fondation","description":"Pour la qualit\u00e9 de la vie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dallemolle.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/dallemolle.ch\/it\/wp-json\/wp\/v2\/laureat\/704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dallemolle.ch\/it\/wp-json\/wp\/v2\/laureat"}],"about":[{"href":"https:\/\/dallemolle.ch\/it\/wp-json\/wp\/v2\/types\/laureat"}],"wp:attachment":[{"href":"https:\/\/dallemolle.ch\/it\/wp-json\/wp\/v2\/media?parent=704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}